{"id":262,"count":1,"description":"","link":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/","name":"di\u00e9go","slug":"diego","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.7 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des di\u00e9go - Madagascar tour operator<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des di\u00e9go - Madagascar tour operator\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/\" \/>\n<meta property=\"og:site_name\" content=\"Madagascar tour operator\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/tag\\\/diego\\\/\",\"url\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/tag\\\/diego\\\/\",\"name\":\"Archives des di\u00e9go - Madagascar tour operator\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/tag\\\/diego\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/tag\\\/diego\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"di\u00e9go\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/\",\"name\":\"Madagascar tour operator\",\"description\":\"Travel specialist in Madagascar | Madagascar tailor-made tour expert, incoming tour operator in Madagascar, organized trip for Madagascar | adventure tour, discovery tour, cultural tour, nature tour, trekking, beach stay and many other themes | Madagascar car rental\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tour-operator-madagascar.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des di\u00e9go - Madagascar tour operator","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/","og_locale":"fr_FR","og_type":"article","og_title":"Archives des di\u00e9go - Madagascar tour operator","og_url":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/","og_site_name":"Madagascar tour operator","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/","url":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/","name":"Archives des di\u00e9go - Madagascar tour operator","isPartOf":{"@id":"https:\/\/tour-operator-madagascar.com\/en\/#website"},"breadcrumb":{"@id":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/tour-operator-madagascar.com\/en\/tag\/diego\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/tour-operator-madagascar.com\/en\/"},{"@type":"ListItem","position":2,"name":"di\u00e9go"}]},{"@type":"WebSite","@id":"https:\/\/tour-operator-madagascar.com\/en\/#website","url":"https:\/\/tour-operator-madagascar.com\/en\/","name":"Madagascar tour operator","description":"Travel specialist in Madagascar | Madagascar tailor-made tour expert, incoming tour operator in Madagascar, organized trip for Madagascar | adventure tour, discovery tour, cultural tour, nature tour, trekking, beach stay and many other themes | Madagascar car rental","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tour-operator-madagascar.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/tour-operator-madagascar.com\/en\/wp-json\/wp\/v2\/tags\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tour-operator-madagascar.com\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/tour-operator-madagascar.com\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/tour-operator-madagascar.com\/en\/wp-json\/wp\/v2\/posts?tags=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}